{"id":2371,"date":"2021-01-07T23:02:48","date_gmt":"2021-01-07T22:02:48","guid":{"rendered":"http:\/\/www.circolospeleologicoromano.it\/csr\/?page_id=2371"},"modified":"2021-03-15T10:32:06","modified_gmt":"2021-03-15T09:32:06","slug":"guy-van-den-steen","status":"publish","type":"page","link":"https:\/\/www.circolospeleologicoromano.it\/csr\/lassociazione\/racconti-e-ricordi\/ricordi-di-soci-1\/guy-van-den-steen","title":{"rendered":"Guy Van den Steen (1906-1999)"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" src=\"http:\/\/www.circolospeleologicoromano.it\/csr\/wp-content\/uploads\/2021\/01\/steen-723x1024.jpg\" alt=\"\" class=\"wp-image-2375\" width=\"347\" height=\"487\"\/><figcaption><em>Guy, risorgenza di Capo Quirino<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>Guy Van Den Steen<\/strong>, scultore belga, conobbe <strong>Carlo Franchetti<\/strong> nel 1939. Di nobili origini, figlio del primo ambasciatore a Roma, Guy coltiva molte passioni e vive nel <strong>castello di Jehay<\/strong> ad Amay, in provincia di Liegi, oggi museo nazionale, dove colleziona opere d\u2019arte ed esegue le sue famose sculture in bronzo. Nell\u2019autobiografia del 1986 ricorder\u00e0 le sue esplorazioni. Guy inizia ad andar per grotte con Carlo Franchetti, presidente del CSR, di cui diviene amico; viene in Italia per \u201cpartecipare alla scoperta di nuove cavit\u00e0 con l\u2019associazione\u201d, Guy afferma che \u00abil solo interesse che presenta per me l\u2019esplorazione d\u2019una grotta \u00e8 di essere il primo a scoprire o il primo a forzare un passaggio. Gli ambienti sconosciuti che possono presentarsi m\u2019attirano e il fatto che non si conosca la finalit\u00e0\u00bb dell\u2019esplorazione, contriamente all\u2019alpinismo, in cui l\u2019obiettivo \u00e8 la vetta, crea un fascino particolare. Con questo spirito Guy partecipa alle esplorazioni nella <strong>risorgenza di Capo Quirino<\/strong>, in cui compie un\u2019operazione esplorativa \u2018canonica\u2019 della speleologia di tutti i tempi, il passaggio del sifone in <strong>apnea<\/strong>. Nella risorgenza di Capo Quirino Guy \u00e8 poi protagonista dello <strong>svuotamento dei sifoni<\/strong> e delle esplorazioni del CSR, durante le quali s\u2019ingegna a trovare soluzioni   per superare gli ostacoli, come i <strong>pali telescopici<\/strong>; sar\u00e0 anche ideatore nella spedizione del 1963 in <strong>Libano <\/strong>di una curiosa ciambella gonfiabile costruita per traversare laghi sotterranei con punti stretti o pseudosifoni. Il 26 marzo del 1960 sui <strong>Monti Carseolani,<\/strong> scopre il \u2018mitico\u2019 passaggio chiave per la continuazione delle esplorazioni a valle del sifone dell\u2019<strong>inghiottitoio di Val de Varr<\/strong>i (Pescorocchiano, Rieti), seguendo la corrente dell\u2019aria tramite il fumo di una sigaretta. <br><\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guy Van Den Steen, scultore belga, conobbe Carlo Franchetti nel 1939. Di nobili origini, figlio del primo ambasciatore a Roma, Guy coltiva molte passioni e vive nel castello di Jehay ad Amay, in provincia di Liegi, oggi museo nazionale, dove colleziona opere d\u2019arte ed esegue le sue famose sculture in\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/www.circolospeleologicoromano.it\/csr\/lassociazione\/racconti-e-ricordi\/ricordi-di-soci-1\/guy-van-den-steen\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":2748,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"spay_email":""},"jetpack_shortlink":"https:\/\/wp.me\/P4fW4I-Cf","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/pages\/2371"}],"collection":[{"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/comments?post=2371"}],"version-history":[{"count":12,"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/pages\/2371\/revisions"}],"predecessor-version":[{"id":5445,"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/pages\/2371\/revisions\/5445"}],"up":[{"embeddable":true,"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/pages\/2748"}],"wp:attachment":[{"href":"https:\/\/www.circolospeleologicoromano.it\/csr\/wp-json\/wp\/v2\/media?parent=2371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}